{"id":58,"count":1,"description":"","link":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/","name":"The Lint King","slug":"the-lint-king","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Lint King Archives - The Lint King<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Lint King Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/\" \/>\n<meta property=\"og:site_name\" content=\"The Lint King\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thelintking.com\/blog\/wp-content\/uploads\/2024\/07\/the-lint-king-dryer-vent-cleaning-experts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheLintKing\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/category\\\/the-lint-king\\\/\",\"url\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/category\\\/the-lint-king\\\/\",\"name\":\"The Lint King Archives - The Lint King\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/category\\\/the-lint-king\\\/#breadcrumb\"},\"inLanguage\":\"en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/category\\\/the-lint-king\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Lint King\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/\",\"name\":\"The Lint King\",\"description\":\"Dryer Vent Cleaning Experts\",\"publisher\":{\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/#organization\"},\"alternateName\":\"Dryer Vent Cleaning\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/#organization\",\"name\":\"The Lint King\",\"alternateName\":\"Dryer Vent Cleaning Experts\",\"url\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-local-dryer-vent-cleaning.png\",\"contentUrl\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-local-dryer-vent-cleaning.png\",\"width\":250,\"height\":250,\"caption\":\"The Lint King\"},\"image\":{\"@id\":\"https:\\\/\\\/thelintking.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thelintking\",\"https:\\\/\\\/x.com\\\/TheLintKing\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/thelintking\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/lintking\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@DryerVentCleaningExperts\\\/\",\"https:\\\/\\\/www.alignable.com\\\/schaumburg-il\\\/the-lint-king-dryer-vent-cleaning-experts\",\"https:\\\/\\\/www.instagram.com\\\/thelintking\\\/\"],\"telephone\":\"2005\",\"legalName\":\"The Lint King Inc.\",\"foundingDate\":\"2005-06-15\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Lint King Archives - The Lint King","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/","og_locale":"en_US","og_type":"article","og_title":"The Lint King Archives","og_url":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/","og_site_name":"The Lint King","og_image":[{"width":1200,"height":675,"url":"https:\/\/thelintking.com\/blog\/wp-content\/uploads\/2024\/07\/the-lint-king-dryer-vent-cleaning-experts.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TheLintKing","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/","url":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/","name":"The Lint King Archives - The Lint King","isPartOf":{"@id":"https:\/\/thelintking.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/#breadcrumb"},"inLanguage":"en"},{"@type":"BreadcrumbList","@id":"https:\/\/thelintking.com\/blog\/category\/the-lint-king\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thelintking.com\/blog\/"},{"@type":"ListItem","position":2,"name":"The Lint King"}]},{"@type":"WebSite","@id":"https:\/\/thelintking.com\/blog\/#website","url":"https:\/\/thelintking.com\/blog\/","name":"The Lint King","description":"Dryer Vent Cleaning Experts","publisher":{"@id":"https:\/\/thelintking.com\/blog\/#organization"},"alternateName":"Dryer Vent Cleaning","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thelintking.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/thelintking.com\/blog\/#organization","name":"The Lint King","alternateName":"Dryer Vent Cleaning Experts","url":"https:\/\/thelintking.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/thelintking.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/thelintking.com\/blog\/wp-content\/uploads\/2020\/09\/cropped-local-dryer-vent-cleaning.png","contentUrl":"https:\/\/thelintking.com\/blog\/wp-content\/uploads\/2020\/09\/cropped-local-dryer-vent-cleaning.png","width":250,"height":250,"caption":"The Lint King"},"image":{"@id":"https:\/\/thelintking.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thelintking","https:\/\/x.com\/TheLintKing","https:\/\/www.linkedin.com\/in\/thelintking\/","https:\/\/www.pinterest.com\/lintking\/","https:\/\/www.youtube.com\/@DryerVentCleaningExperts\/","https:\/\/www.alignable.com\/schaumburg-il\/the-lint-king-dryer-vent-cleaning-experts","https:\/\/www.instagram.com\/thelintking\/"],"telephone":"2005","legalName":"The Lint King Inc.","foundingDate":"2005-06-15","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/thelintking.com\/blog\/wp-json\/wp\/v2\/categories\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelintking.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/thelintking.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/thelintking.com\/blog\/wp-json\/wp\/v2\/posts?categories=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}